{"id":10,"count":2,"description":"","link":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/","name":"Education","slug":"education","taxonomy":"category","parent":6,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Education Archives - Equality: Anti-Racism<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Education Archives - Equality: Anti-Racism\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/\" \/>\n<meta property=\"og:site_name\" content=\"Equality: Anti-Racism\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/category\\\/educational-resources\\\/education\\\/\",\"url\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/category\\\/educational-resources\\\/education\\\/\",\"name\":\"Education Archives - Equality: Anti-Racism\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/category\\\/educational-resources\\\/education\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/category\\\/educational-resources\\\/education\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educational Resources\",\"item\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/category\\\/educational-resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Education\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#website\",\"url\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/\",\"name\":\"Equality: Anti-Racism\",\"description\":\"Promoting Equality in Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#organization\",\"name\":\"Equality: Anti-Racism\",\"url\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/eis.jpg\",\"contentUrl\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/eis.jpg\",\"width\":164,\"height\":90,\"caption\":\"Equality: Anti-Racism\"},\"image\":{\"@id\":\"https:\\\/\\\/equality.eis.org.uk\\\/anti-racism\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Education Archives - Equality: Anti-Racism","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/","og_locale":"en_US","og_type":"article","og_title":"Education Archives - Equality: Anti-Racism","og_url":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/","og_site_name":"Equality: Anti-Racism","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/","url":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/","name":"Education Archives - Equality: Anti-Racism","isPartOf":{"@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#website"},"breadcrumb":{"@id":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/education\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equality.eis.org.uk\/anti-racism\/"},{"@type":"ListItem","position":2,"name":"Educational Resources","item":"https:\/\/equality.eis.org.uk\/anti-racism\/category\/educational-resources\/"},{"@type":"ListItem","position":3,"name":"Education"}]},{"@type":"WebSite","@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#website","url":"https:\/\/equality.eis.org.uk\/anti-racism\/","name":"Equality: Anti-Racism","description":"Promoting Equality in Education","publisher":{"@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equality.eis.org.uk\/anti-racism\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#organization","name":"Equality: Anti-Racism","url":"https:\/\/equality.eis.org.uk\/anti-racism\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#\/schema\/logo\/image\/","url":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-content\/uploads\/2023\/05\/eis.jpg","contentUrl":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-content\/uploads\/2023\/05\/eis.jpg","width":164,"height":90,"caption":"Equality: Anti-Racism"},"image":{"@id":"https:\/\/equality.eis.org.uk\/anti-racism\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-json\/wp\/v2\/categories\/6"}],"wp:post_type":[{"href":"https:\/\/equality.eis.org.uk\/anti-racism\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}